{"id":2806,"date":"2025-04-14T07:54:22","date_gmt":"2025-04-14T07:54:22","guid":{"rendered":"https:\/\/radiovecinaldecalama.cl\/?p=2806"},"modified":"2025-04-14T07:56:22","modified_gmt":"2025-04-14T07:56:22","slug":"62-considera-que-tener-hijos-es-mas-dificil-de-lo-que-imaginaba-y-entre-aquellos-que-no-tienen-hijos-58-no-quiere-tenerlos-hoy","status":"publish","type":"post","link":"https:\/\/radiovecinaldecalama.cl\/index.php\/2025\/04\/14\/62-considera-que-tener-hijos-es-mas-dificil-de-lo-que-imaginaba-y-entre-aquellos-que-no-tienen-hijos-58-no-quiere-tenerlos-hoy\/","title":{"rendered":"62% considera que tener hijos es m\u00e1s dif\u00edcil de lo que imaginaba y entre aquellos que no tienen hijos, 58% no quiere tenerlos hoy"},"content":{"rendered":"<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Seg\u00fan la encuesta Cadem:<\/span><\/span><\/p>\n<ul>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Las principales razones por las que los chilenos tienen cada vez menos hijos son los altos costos econ\u00f3micos (53%), que se prioriza el desarrollo profesional (29%), que se prioriza el bienestar personal sin responsabilidades a largo plazo (28%) y que el mundo es un lugar muy hostil (28%).<\/span><\/span><\/li>\n<li><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Adem\u00e1s, el 80% est\u00e1 muy de acuerdo con que a las personas de hoy les importa m\u00e1s el desarrollo profesional que tener hijos, el 77% con que tener hijos es muy caro econ\u00f3micamente y el 72% con que la gente prefiere tener mascotas a tener hijos.<\/span><\/span><\/li>\n<li><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2807\" src=\"https:\/\/radiovecinaldecalama.cl\/wp-content\/uploads\/2025\/04\/banner-horizontal2-1-2025-04-10T150815.409-300x161.png\" alt=\"\" width=\"358\" height=\"192\" srcset=\"https:\/\/radiovecinaldecalama.cl\/wp-content\/uploads\/2025\/04\/banner-horizontal2-1-2025-04-10T150815.409-300x161.png 300w, https:\/\/radiovecinaldecalama.cl\/wp-content\/uploads\/2025\/04\/banner-horizontal2-1-2025-04-10T150815.409-1024x549.png 1024w, https:\/\/radiovecinaldecalama.cl\/wp-content\/uploads\/2025\/04\/banner-horizontal2-1-2025-04-10T150815.409-768x412.png 768w, https:\/\/radiovecinaldecalama.cl\/wp-content\/uploads\/2025\/04\/banner-horizontal2-1-2025-04-10T150815.409.png 1107w\" sizes=\"auto, (max-width: 358px) 100vw, 358px\" \/><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seg\u00fan la encuesta Cadem: Las principales razones por las que los chilenos tienen cada vez menos hijos son los altos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2807,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[11],"tags":[14],"class_list":["post-2806","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-destacados"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>62% considera que tener hijos es m\u00e1s dif\u00edcil de lo que imaginaba y entre aquellos que no tienen hijos, 58% no quiere tenerlos hoy -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiovecinaldecalama.cl\/index.php\/2025\/04\/14\/62-considera-que-tener-hijos-es-mas-dificil-de-lo-que-imaginaba-y-entre-aquellos-que-no-tienen-hijos-58-no-quiere-tenerlos-hoy\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"62% considera que tener hijos es m\u00e1s dif\u00edcil de lo que imaginaba y entre aquellos que no tienen hijos, 58% no quiere tenerlos hoy -\" \/>\n<meta property=\"og:description\" content=\"Seg\u00fan la encuesta Cadem: Las principales razones por las que los chilenos tienen cada vez menos hijos son los altos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiovecinaldecalama.cl\/index.php\/2025\/04\/14\/62-considera-que-tener-hijos-es-mas-dificil-de-lo-que-imaginaba-y-entre-aquellos-que-no-tienen-hijos-58-no-quiere-tenerlos-hoy\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-14T07:54:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-14T07:56:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radiovecinaldecalama.cl\/wp-content\/uploads\/2025\/04\/banner-horizontal2-1-2025-04-10T150815.409.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1107\" \/>\n\t<meta property=\"og:image:height\" content=\"594\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/radiovecinaldecalama.cl\/index.php\/2025\/04\/14\/62-considera-que-tener-hijos-es-mas-dificil-de-lo-que-imaginaba-y-entre-aquellos-que-no-tienen-hijos-58-no-quiere-tenerlos-hoy\/\",\"url\":\"https:\/\/radiovecinaldecalama.cl\/index.php\/2025\/04\/14\/62-considera-que-tener-hijos-es-mas-dificil-de-lo-que-imaginaba-y-entre-aquellos-que-no-tienen-hijos-58-no-quiere-tenerlos-hoy\/\",\"name\":\"62% considera que tener hijos es m\u00e1s dif\u00edcil de lo que imaginaba y entre aquellos que no tienen hijos, 58% no quiere tenerlos hoy -\",\"isPartOf\":{\"@id\":\"https:\/\/radiovecinaldecalama.cl\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/radiovecinaldecalama.cl\/index.php\/2025\/04\/14\/62-considera-que-tener-hijos-es-mas-dificil-de-lo-que-imaginaba-y-entre-aquellos-que-no-tienen-hijos-58-no-quiere-tenerlos-hoy\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/radiovecinaldecalama.cl\/index.php\/2025\/04\/14\/62-considera-que-tener-hijos-es-mas-dificil-de-lo-que-imaginaba-y-entre-aquellos-que-no-tienen-hijos-58-no-quiere-tenerlos-hoy\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiovecinaldecalama.cl\/wp-content\/uploads\/2025\/04\/banner-horizontal2-1-2025-04-10T150815.409.png\",\"datePublished\":\"2025-04-14T07:54:22+00:00\",\"dateModified\":\"2025-04-14T07:56:22+00:00\",\"author\":{\"@id\":\"https:\/\/radiovecinaldecalama.cl\/#\/schema\/person\/f9904e81e127490127c95731156cd97e\"},\"breadcrumb\":{\"@id\":\"https:\/\/radiovecinaldecalama.cl\/index.php\/2025\/04\/14\/62-considera-que-tener-hijos-es-mas-dificil-de-lo-que-imaginaba-y-entre-aquellos-que-no-tienen-hijos-58-no-quiere-tenerlos-hoy\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/radiovecinaldecalama.cl\/index.php\/2025\/04\/14\/62-considera-que-tener-hijos-es-mas-dificil-de-lo-que-imaginaba-y-entre-aquellos-que-no-tienen-hijos-58-no-quiere-tenerlos-hoy\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/radiovecinaldecalama.cl\/index.php\/2025\/04\/14\/62-considera-que-tener-hijos-es-mas-dificil-de-lo-que-imaginaba-y-entre-aquellos-que-no-tienen-hijos-58-no-quiere-tenerlos-hoy\/#primaryimage\",\"url\":\"https:\/\/radiovecinaldecalama.cl\/wp-content\/uploads\/2025\/04\/banner-horizontal2-1-2025-04-10T150815.409.png\",\"contentUrl\":\"https:\/\/radiovecinaldecalama.cl\/wp-content\/uploads\/2025\/04\/banner-horizontal2-1-2025-04-10T150815.409.png\",\"width\":1107,\"height\":594},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/radiovecinaldecalama.cl\/index.php\/2025\/04\/14\/62-considera-que-tener-hijos-es-mas-dificil-de-lo-que-imaginaba-y-entre-aquellos-que-no-tienen-hijos-58-no-quiere-tenerlos-hoy\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/radiovecinaldecalama.cl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"62% considera que tener hijos es m\u00e1s dif\u00edcil de lo que imaginaba y entre aquellos que no tienen hijos, 58% no quiere tenerlos hoy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/radiovecinaldecalama.cl\/#website\",\"url\":\"https:\/\/radiovecinaldecalama.cl\/\",\"name\":\"\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/radiovecinaldecalama.cl\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/radiovecinaldecalama.cl\/#\/schema\/person\/f9904e81e127490127c95731156cd97e\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/radiovecinaldecalama.cl\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/50d4f6bd46f2b8f4fd92164c4aec3e4c3788ee0ee9a6b11af790cae3ba095801?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/50d4f6bd46f2b8f4fd92164c4aec3e4c3788ee0ee9a6b11af790cae3ba095801?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\/\/radiovecinaldecalama.cl\"],\"url\":\"https:\/\/radiovecinaldecalama.cl\/index.php\/author\/admin_2npympei\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"62% considera que tener hijos es m\u00e1s dif\u00edcil de lo que imaginaba y entre aquellos que no tienen hijos, 58% no quiere tenerlos hoy -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiovecinaldecalama.cl\/index.php\/2025\/04\/14\/62-considera-que-tener-hijos-es-mas-dificil-de-lo-que-imaginaba-y-entre-aquellos-que-no-tienen-hijos-58-no-quiere-tenerlos-hoy\/","og_locale":"es_ES","og_type":"article","og_title":"62% considera que tener hijos es m\u00e1s dif\u00edcil de lo que imaginaba y entre aquellos que no tienen hijos, 58% no quiere tenerlos hoy -","og_description":"Seg\u00fan la encuesta Cadem: Las principales razones por las que los chilenos tienen cada vez menos hijos son los altos [&hellip;]","og_url":"https:\/\/radiovecinaldecalama.cl\/index.php\/2025\/04\/14\/62-considera-que-tener-hijos-es-mas-dificil-de-lo-que-imaginaba-y-entre-aquellos-que-no-tienen-hijos-58-no-quiere-tenerlos-hoy\/","article_published_time":"2025-04-14T07:54:22+00:00","article_modified_time":"2025-04-14T07:56:22+00:00","og_image":[{"width":1107,"height":594,"url":"https:\/\/radiovecinaldecalama.cl\/wp-content\/uploads\/2025\/04\/banner-horizontal2-1-2025-04-10T150815.409.png","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/radiovecinaldecalama.cl\/index.php\/2025\/04\/14\/62-considera-que-tener-hijos-es-mas-dificil-de-lo-que-imaginaba-y-entre-aquellos-que-no-tienen-hijos-58-no-quiere-tenerlos-hoy\/","url":"https:\/\/radiovecinaldecalama.cl\/index.php\/2025\/04\/14\/62-considera-que-tener-hijos-es-mas-dificil-de-lo-que-imaginaba-y-entre-aquellos-que-no-tienen-hijos-58-no-quiere-tenerlos-hoy\/","name":"62% considera que tener hijos es m\u00e1s dif\u00edcil de lo que imaginaba y entre aquellos que no tienen hijos, 58% no quiere tenerlos hoy -","isPartOf":{"@id":"https:\/\/radiovecinaldecalama.cl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radiovecinaldecalama.cl\/index.php\/2025\/04\/14\/62-considera-que-tener-hijos-es-mas-dificil-de-lo-que-imaginaba-y-entre-aquellos-que-no-tienen-hijos-58-no-quiere-tenerlos-hoy\/#primaryimage"},"image":{"@id":"https:\/\/radiovecinaldecalama.cl\/index.php\/2025\/04\/14\/62-considera-que-tener-hijos-es-mas-dificil-de-lo-que-imaginaba-y-entre-aquellos-que-no-tienen-hijos-58-no-quiere-tenerlos-hoy\/#primaryimage"},"thumbnailUrl":"https:\/\/radiovecinaldecalama.cl\/wp-content\/uploads\/2025\/04\/banner-horizontal2-1-2025-04-10T150815.409.png","datePublished":"2025-04-14T07:54:22+00:00","dateModified":"2025-04-14T07:56:22+00:00","author":{"@id":"https:\/\/radiovecinaldecalama.cl\/#\/schema\/person\/f9904e81e127490127c95731156cd97e"},"breadcrumb":{"@id":"https:\/\/radiovecinaldecalama.cl\/index.php\/2025\/04\/14\/62-considera-que-tener-hijos-es-mas-dificil-de-lo-que-imaginaba-y-entre-aquellos-que-no-tienen-hijos-58-no-quiere-tenerlos-hoy\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiovecinaldecalama.cl\/index.php\/2025\/04\/14\/62-considera-que-tener-hijos-es-mas-dificil-de-lo-que-imaginaba-y-entre-aquellos-que-no-tienen-hijos-58-no-quiere-tenerlos-hoy\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/radiovecinaldecalama.cl\/index.php\/2025\/04\/14\/62-considera-que-tener-hijos-es-mas-dificil-de-lo-que-imaginaba-y-entre-aquellos-que-no-tienen-hijos-58-no-quiere-tenerlos-hoy\/#primaryimage","url":"https:\/\/radiovecinaldecalama.cl\/wp-content\/uploads\/2025\/04\/banner-horizontal2-1-2025-04-10T150815.409.png","contentUrl":"https:\/\/radiovecinaldecalama.cl\/wp-content\/uploads\/2025\/04\/banner-horizontal2-1-2025-04-10T150815.409.png","width":1107,"height":594},{"@type":"BreadcrumbList","@id":"https:\/\/radiovecinaldecalama.cl\/index.php\/2025\/04\/14\/62-considera-que-tener-hijos-es-mas-dificil-de-lo-que-imaginaba-y-entre-aquellos-que-no-tienen-hijos-58-no-quiere-tenerlos-hoy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/radiovecinaldecalama.cl\/"},{"@type":"ListItem","position":2,"name":"62% considera que tener hijos es m\u00e1s dif\u00edcil de lo que imaginaba y entre aquellos que no tienen hijos, 58% no quiere tenerlos hoy"}]},{"@type":"WebSite","@id":"https:\/\/radiovecinaldecalama.cl\/#website","url":"https:\/\/radiovecinaldecalama.cl\/","name":"","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiovecinaldecalama.cl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/radiovecinaldecalama.cl\/#\/schema\/person\/f9904e81e127490127c95731156cd97e","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/radiovecinaldecalama.cl\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/50d4f6bd46f2b8f4fd92164c4aec3e4c3788ee0ee9a6b11af790cae3ba095801?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50d4f6bd46f2b8f4fd92164c4aec3e4c3788ee0ee9a6b11af790cae3ba095801?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/radiovecinaldecalama.cl"],"url":"https:\/\/radiovecinaldecalama.cl\/index.php\/author\/admin_2npympei\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/radiovecinaldecalama.cl\/wp-content\/uploads\/2025\/04\/banner-horizontal2-1-2025-04-10T150815.409.png",1107,594,false],"thumbnail":["https:\/\/radiovecinaldecalama.cl\/wp-content\/uploads\/2025\/04\/banner-horizontal2-1-2025-04-10T150815.409-150x150.png",150,150,true],"medium":["https:\/\/radiovecinaldecalama.cl\/wp-content\/uploads\/2025\/04\/banner-horizontal2-1-2025-04-10T150815.409-300x161.png",300,161,true],"medium_large":["https:\/\/radiovecinaldecalama.cl\/wp-content\/uploads\/2025\/04\/banner-horizontal2-1-2025-04-10T150815.409-768x412.png",768,412,true],"large":["https:\/\/radiovecinaldecalama.cl\/wp-content\/uploads\/2025\/04\/banner-horizontal2-1-2025-04-10T150815.409-1024x549.png",1024,549,true],"1536x1536":["https:\/\/radiovecinaldecalama.cl\/wp-content\/uploads\/2025\/04\/banner-horizontal2-1-2025-04-10T150815.409.png",1107,594,false],"2048x2048":["https:\/\/radiovecinaldecalama.cl\/wp-content\/uploads\/2025\/04\/banner-horizontal2-1-2025-04-10T150815.409.png",1107,594,false]},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/radiovecinaldecalama.cl\/index.php\/author\/admin_2npympei\/"},"uagb_comment_info":0,"uagb_excerpt":"Seg\u00fan la encuesta Cadem: Las principales razones por las que los chilenos tienen cada vez menos hijos son los altos [&hellip;]","_links":{"self":[{"href":"https:\/\/radiovecinaldecalama.cl\/index.php\/wp-json\/wp\/v2\/posts\/2806","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiovecinaldecalama.cl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiovecinaldecalama.cl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiovecinaldecalama.cl\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radiovecinaldecalama.cl\/index.php\/wp-json\/wp\/v2\/comments?post=2806"}],"version-history":[{"count":2,"href":"https:\/\/radiovecinaldecalama.cl\/index.php\/wp-json\/wp\/v2\/posts\/2806\/revisions"}],"predecessor-version":[{"id":2809,"href":"https:\/\/radiovecinaldecalama.cl\/index.php\/wp-json\/wp\/v2\/posts\/2806\/revisions\/2809"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiovecinaldecalama.cl\/index.php\/wp-json\/wp\/v2\/media\/2807"}],"wp:attachment":[{"href":"https:\/\/radiovecinaldecalama.cl\/index.php\/wp-json\/wp\/v2\/media?parent=2806"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiovecinaldecalama.cl\/index.php\/wp-json\/wp\/v2\/categories?post=2806"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiovecinaldecalama.cl\/index.php\/wp-json\/wp\/v2\/tags?post=2806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}